{"id":4214,"date":"2017-11-29T05:51:09","date_gmt":"2017-11-29T05:51:09","guid":{"rendered":"http:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif"},"modified":"2017-11-29T05:51:14","modified_gmt":"2017-11-29T05:51:14","slug":"diy-surprise-message-confetti-poppers-tutorial","status":"inherit","type":"attachment","link":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/diy-surprise-message-confetti-poppers-tutorial","title":{"rendered":"DIY-Surprise-Message-Confetti-Poppers-Tutorial"},"author":471,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-4214","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIY-Surprise-Message-Confetti-Poppers-Tutorial - Fashion Lifestyle Trends<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIY-Surprise-Message-Confetti-Poppers-Tutorial - Fashion Lifestyle Trends\" \/>\n<meta property=\"og:description\" content=\"Source\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif\" \/>\n<meta property=\"og:site_name\" content=\"Fashion Lifestyle Trends\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-29T05:51:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif\",\"url\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif\",\"name\":\"DIY-Surprise-Message-Confetti-Poppers-Tutorial - Fashion Lifestyle Trends\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/#website\"},\"datePublished\":\"2017-11-29T05:51:09+00:00\",\"dateModified\":\"2017-11-29T05:51:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIY-Surprise-Message-Confetti-Poppers-Tutorial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/#website\",\"url\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/\",\"name\":\"Fashion Lifestyle Trends\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIY-Surprise-Message-Confetti-Poppers-Tutorial - Fashion Lifestyle Trends","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif","og_locale":"en_US","og_type":"article","og_title":"DIY-Surprise-Message-Confetti-Poppers-Tutorial - Fashion Lifestyle Trends","og_description":"Source","og_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif","og_site_name":"Fashion Lifestyle Trends","article_modified_time":"2017-11-29T05:51:14+00:00","og_image":[{"width":600,"height":900,"url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif","type":"image\/gif"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif","url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif","name":"DIY-Surprise-Message-Confetti-Poppers-Tutorial - Fashion Lifestyle Trends","isPartOf":{"@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/#website"},"datePublished":"2017-11-29T05:51:09+00:00","dateModified":"2017-11-29T05:51:14+00:00","breadcrumb":{"@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends"},{"@type":"ListItem","position":2,"name":"DIY-Surprise-Message-Confetti-Poppers-Tutorial"}]},{"@type":"WebSite","@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/#website","url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/","name":"Fashion Lifestyle Trends","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif'><img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-533x800.gif\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-533x800.gif 533w, https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-67x100.gif 67w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href=\"https:\/\/studiodiy.com\/2013\/06\/25\/diy-surprise-message-confetti-poppers\/\" target=\"_blank\">Source<\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/gif","media_details":{"width":600,"height":900,"file":"2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif","sizes":{"thumbnail":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial-290x290.gif","width":290,"height":290,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-290x290.gif"},"medium":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial-533x800.gif","width":533,"height":800,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-533x800.gif"},"admin-thumbs":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial-67x100.gif","width":67,"height":100,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-67x100.gif"},"mh-magazine-slider":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial-600x438.gif","width":600,"height":438,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-600x438.gif"},"mh-magazine-content":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial-600x381.gif","width":600,"height":381,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-600x381.gif"},"mh-magazine-large":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial-600x509.gif","width":600,"height":509,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-600x509.gif"},"mh-magazine-medium":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial-326x245.gif","width":326,"height":245,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-326x245.gif"},"mh-magazine-small":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial-80x60.gif","width":80,"height":60,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-80x60.gif"},"wp_rp_thumbnail":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial-150x150.gif","width":150,"height":150,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-150x150.gif"},"wp_review_small":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial-65x65.gif","width":65,"height":65,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-65x65.gif"},"wp_review_large":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial-320x240.gif","width":320,"height":240,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial-320x240.gif"},"full":{"file":"DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif","width":600,"height":900,"mime_type":"image\/gif","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2017\/11\/DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif","filename":"DIY-Surprise-Message-Confetti-Poppers-Tutorial.gif","filesize":1637098,"_links":{"self":[{"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/media\/4214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/users\/471"}],"replies":[{"embeddable":true,"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/comments?post=4214"}]}}