{"id":22488,"date":"2022-09-27T10:30:36","date_gmt":"2022-09-27T10:30:36","guid":{"rendered":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg"},"modified":"2022-09-27T10:30:36","modified_gmt":"2022-09-27T10:30:36","slug":"navy-nails3-2","status":"inherit","type":"attachment","link":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/navy-nails3-2","title":{"rendered":"navy-nails3"},"author":471,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-22488","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>navy-nails3 - Fashion Lifestyle Trends<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"navy-nails3 - Fashion Lifestyle Trends\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fashion Lifestyle Trends\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"794\" \/>\n\t<meta property=\"og:image:height\" content=\"794\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/navy-nails3-1.jpg\",\"url\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/navy-nails3-1.jpg\",\"name\":\"navy-nails3 - Fashion Lifestyle Trends\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/#website\"},\"datePublished\":\"2022-09-27T10:30:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/navy-nails3-1.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/navy-nails3-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/navy-nails3-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"navy-nails3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/#website\",\"url\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/\",\"name\":\"Fashion Lifestyle Trends\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"navy-nails3 - Fashion Lifestyle Trends","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg","og_locale":"en_US","og_type":"article","og_title":"navy-nails3 - Fashion Lifestyle Trends","og_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg","og_site_name":"Fashion Lifestyle Trends","og_image":[{"width":794,"height":794,"url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg","url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg","name":"navy-nails3 - Fashion Lifestyle Trends","isPartOf":{"@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/#website"},"datePublished":"2022-09-27T10:30:36+00:00","breadcrumb":{"@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends"},{"@type":"ListItem","position":2,"name":"navy-nails3"}]},{"@type":"WebSite","@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/#website","url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/","name":"Fashion Lifestyle Trends","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"794\" height=\"794\" src=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg 794w, https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-290x290.jpg 290w, https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-768x768.jpg 768w, https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-100x100.jpg 100w, https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-65x65.jpg 65w\" sizes=\"auto, (max-width: 794px) 100vw, 794px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":794,"height":794,"file":"2022\/09\/navy-nails3-1.jpg","filesize":148866,"sizes":{"thumbnail":{"file":"navy-nails3-1-290x290.jpg","width":290,"height":290,"filesize":18028,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-290x290.jpg"},"medium_large":{"file":"navy-nails3-1-768x768.jpg","width":768,"height":768,"filesize":89699,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-768x768.jpg"},"admin-thumbs":{"file":"navy-nails3-1-100x100.jpg","width":100,"height":100,"filesize":3909,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-100x100.jpg"},"mh-magazine-slider":{"file":"navy-nails3-1-794x438.jpg","width":794,"height":438,"filesize":62764,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-794x438.jpg"},"mh-magazine-content":{"file":"navy-nails3-1-678x381.jpg","width":678,"height":381,"filesize":42696,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-678x381.jpg"},"mh-magazine-large":{"file":"navy-nails3-1-678x509.jpg","width":678,"height":509,"filesize":57001,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-678x509.jpg"},"mh-magazine-medium":{"file":"navy-nails3-1-326x245.jpg","width":326,"height":245,"filesize":16816,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-326x245.jpg"},"mh-magazine-small":{"file":"navy-nails3-1-80x60.jpg","width":80,"height":60,"filesize":2370,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-80x60.jpg"},"wp_review_small":{"file":"navy-nails3-1-65x65.jpg","width":65,"height":65,"filesize":2380,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-65x65.jpg"},"wp_review_large":{"file":"navy-nails3-1-320x240.jpg","width":320,"height":240,"filesize":16011,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1-320x240.jpg"},"full":{"file":"navy-nails3-1.jpg","width":794,"height":794,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/navy-nails3-1.jpg","_links":{"self":[{"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/media\/22488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/users\/471"}],"replies":[{"embeddable":true,"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/comments?post=22488"}]}}