{"id":22223,"date":"2022-09-24T14:03:30","date_gmt":"2022-09-24T14:03:30","guid":{"rendered":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg"},"modified":"2022-09-24T14:03:30","modified_gmt":"2022-09-24T14:03:30","slug":"coffin-long-winter-nails","status":"inherit","type":"attachment","link":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/coffin-long-winter-nails","title":{"rendered":"Coffin-Long-Winter-Nails"},"author":471,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-22223","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coffin-Long-Winter-Nails - Fashion Lifestyle Trends<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coffin-Long-Winter-Nails - Fashion Lifestyle Trends\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fashion Lifestyle Trends\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1227\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Coffin-Long-Winter-Nails.jpg\",\"url\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Coffin-Long-Winter-Nails.jpg\",\"name\":\"Coffin-Long-Winter-Nails - Fashion Lifestyle Trends\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/#website\"},\"datePublished\":\"2022-09-24T14:03:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Coffin-Long-Winter-Nails.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Coffin-Long-Winter-Nails.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Coffin-Long-Winter-Nails.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coffin-Long-Winter-Nails\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/#website\",\"url\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/\",\"name\":\"Fashion Lifestyle Trends\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.papaganlar.net\\\/fashion-lifestyle-trends\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coffin-Long-Winter-Nails - Fashion Lifestyle Trends","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg","og_locale":"en_US","og_type":"article","og_title":"Coffin-Long-Winter-Nails - Fashion Lifestyle Trends","og_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg","og_site_name":"Fashion Lifestyle Trends","og_image":[{"width":1080,"height":1227,"url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg","url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg","name":"Coffin-Long-Winter-Nails - Fashion Lifestyle Trends","isPartOf":{"@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/#website"},"datePublished":"2022-09-24T14:03:30+00:00","breadcrumb":{"@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends"},{"@type":"ListItem","position":2,"name":"Coffin-Long-Winter-Nails"}]},{"@type":"WebSite","@id":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/#website","url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/","name":"Fashion Lifestyle Trends","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"704\" height=\"800\" src=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-704x800.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-704x800.jpg 704w, https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-768x873.jpg 768w, https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-88x100.jpg 88w, https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg 1080w\" sizes=\"auto, (max-width: 704px) 100vw, 704px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1080,"height":1227,"file":"2022\/09\/Coffin-Long-Winter-Nails.jpg","filesize":73577,"sizes":{"medium":{"file":"Coffin-Long-Winter-Nails-704x800.jpg","width":704,"height":800,"filesize":79598,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-704x800.jpg"},"thumbnail":{"file":"Coffin-Long-Winter-Nails-290x290.jpg","width":290,"height":290,"filesize":16676,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-290x290.jpg"},"medium_large":{"file":"Coffin-Long-Winter-Nails-768x873.jpg","width":768,"height":873,"filesize":91798,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-768x873.jpg"},"admin-thumbs":{"file":"Coffin-Long-Winter-Nails-88x100.jpg","width":88,"height":100,"filesize":3181,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-88x100.jpg"},"mh-magazine-slider":{"file":"Coffin-Long-Winter-Nails-1030x438.jpg","width":1030,"height":438,"filesize":61253,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-1030x438.jpg"},"mh-magazine-content":{"file":"Coffin-Long-Winter-Nails-678x381.jpg","width":678,"height":381,"filesize":40709,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-678x381.jpg"},"mh-magazine-large":{"file":"Coffin-Long-Winter-Nails-678x509.jpg","width":678,"height":509,"filesize":52439,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-678x509.jpg"},"mh-magazine-medium":{"file":"Coffin-Long-Winter-Nails-326x245.jpg","width":326,"height":245,"filesize":15815,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-326x245.jpg"},"mh-magazine-small":{"file":"Coffin-Long-Winter-Nails-80x60.jpg","width":80,"height":60,"filesize":2078,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-80x60.jpg"},"wp_review_small":{"file":"Coffin-Long-Winter-Nails-65x65.jpg","width":65,"height":65,"filesize":2119,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-65x65.jpg"},"wp_review_large":{"file":"Coffin-Long-Winter-Nails-320x240.jpg","width":320,"height":240,"filesize":14906,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails-320x240.jpg"},"full":{"file":"Coffin-Long-Winter-Nails.jpg","width":1080,"height":1227,"mime_type":"image\/jpeg","source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-content\/uploads\/2022\/09\/Coffin-Long-Winter-Nails.jpg","_links":{"self":[{"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/media\/22223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/users\/471"}],"replies":[{"embeddable":true,"href":"https:\/\/www.papaganlar.net\/fashion-lifestyle-trends\/wp-json\/wp\/v2\/comments?post=22223"}]}}